{"id":4444,"date":"2026-04-28T12:49:22","date_gmt":"2026-04-28T10:49:22","guid":{"rendered":"https:\/\/www.soukup.de\/selbst-denken\/?page_id=4444"},"modified":"2026-07-11T14:27:19","modified_gmt":"2026-07-11T12:27:19","slug":"1-1-5-die-korrektur-des-traditionellen-denkens-in-der-moderne-ii","status":"publish","type":"page","link":"https:\/\/www.soukup.de\/selbst-denken\/buch\/1-einleitung-kurz\/1-1-1-das-traditionelle-denken\/1-1-5-die-korrektur-des-traditionellen-denkens-in-der-moderne-ii\/","title":{"rendered":"1.1.8.  Vom Subjekt \u00fcber dessen &#8222;Tod&#8220; zur Subjektivit\u00e4t"},"content":{"rendered":"<p style=\"text-align: justify;\">Vormodern verstanden sich die traditionellen Subjekte im wesentlichen als <em>Gesch\u00f6pfe von Gottes Gnaden<\/em>. Sie wurden \u2013 ohne zu wissen, warum und wozu \u2013 in eine vorgegebene (St\u00e4nde-)Ordnung hineingeboren, in der sie einen bestimmten Platz einzunehmen und eine definierte Aufgabe zu erf\u00fcllen hatten; das war ihre Essenz, ihr Wesen oder Was. Der Sinn des Lebens bestand darin, dies in Demut anzunehmen, um \u2013 gegebenenfalls \u2013 daf\u00fcr im Jenseits einmal belohnt zu werden\u00a0 \u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Die Subjekte galten \u2013 wie alle Seienden \u2013 als substanziell oder mit sich selbst identisch und besa\u00dfen, im Gegensatz zu den Objekten, nat\u00fcrlich eine Seele. Aber sie waren nicht autonom, das hei\u00dft ihre Freiheit wurde nicht als Selbstbestimmung gedacht, sondern im wesentlichen moralisch verstanden; Freiheit bedeutete, sich gl\u00e4ubig dem Willen Gottes unterzuordnen.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Das \u00e4nderte sich in der Moderne grundlegend.\u00a0Die Subjekte<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; blieben zwar weiterhin Seiende,<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; wurden aber souver\u00e4ner oder unabh\u00e4ngiger,<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; erfuhren sich zunehmend als autonom, selbstbestimmend bzw. eigenverantwortlich.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Besonders wichtige Denker auf diesem Weg waren beispielsweise Descartes, Kant, Hegel und Husserl.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Die daraus resutierende Philosophie \u2013 zumeist als eine solche <em>des Subjekts bzw. Bewu\u00dftseins<\/em> bezeichnet \u2013 neigt sich schon lange wieder ihrem Ende zu. Entscheidend daf\u00fcr war nicht zuletzt der erste Weltkrieg. Viele Geisteswissenschaftler verzweifelten an einem Denken, welches dazu f\u00fchrte, da\u00df die (angeblich) gebildetsten und aufgekl\u00e4rtesten Nationen der Welt zu so einem Hinschlachten f\u00e4hig sind.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Irgendetwas kann hier nicht stimmen; der &#8222;Tod des Subjekts&#8220; im 20. Jahrhundert geh\u00f6rt zur Suche nach einer Antwort.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Wir brechen nat\u00fcrlich ebenfalls mit dieser Tradition; freilich aus einem ganz anderen Grund, n\u00e4mlich <em>weil die Subjekte der Bewu\u00dftseins-Philosohie weiterhin Seiende sind<\/em>.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Um unser prinzipiell andersartiges Denken anzudeuten, sprechen wir <em>bei den postmodernen &#8222;Subjekten&#8220; im weiteren von Subjektivit\u00e4ten<\/em>.\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Sie werden nicht substanziell gedacht und besitzen somit insbesondere keine Seele; vielmehr bestehen die Subjektivit\u00e4ten in der <em>Einheit von Verstricktem und Antwortendem: <\/em><\/p>\n<p class=\"Indent\" style=\"text-align: justify;\"><em>Subjektivit\u00e4t\u00a0 \u00a0=\u00a0 \u00a0{ Verstrickter + Antwortender }<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Den Verstrickten hatten wir in Abschnitt 1.1.3. eingef\u00fchrt; er ist die Dativ- bzw. Akkusativ-Subjektivit\u00e4t:<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; <em>Nicht &#8222;ich handle&#8220;, &#8222;denke&#8220; oder &#8222;wei\u00df&#8220; . . .<\/em>, sondern<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; <em>&#8222;mir geht nahe&#8220;, &#8222;mich betrifft&#8220;, &#8222;interessiert&#8220; oder &#8222;ber\u00fchrt&#8220; . . .<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Schlage ich mir beim Bauen versehentlich mit dem Hammer auf den Daumen, bin ich ein Verstrickter. Vielleicht \u00e4rgert mich mein eigenes Ungeschick, aber ich f\u00fchle oder erlebe mich nicht als angesprochen; weder vom Hammer noch von der mangelhaften \u00dcbung.\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Wenn ich dagegen spazieren gehe, M\u00fcll am Stra\u00dfenrand sehe, gegr\u00fc\u00dft werde oder \u00fcber ein Problem nachdenke, kann ich mich <em>zus\u00e4tzlich als angesprochen erfahren<\/em>.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\"><em>Geschieht das<\/em>, <em>mu\u00df<\/em> ich antworten \u2013 nicht aus moralischen, sondern aus rein logischen Gr\u00fcnden \u2013, denn <em>auch das Nicht-Antworten-Wollen auf ein Sich-angesprochen-F\u00fchlen ist ein Antworten<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>Wodurch ich mich ansprechen oder infrage stellen lasse<\/em>, ist meines Erachtens vollkommen offen.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Emmanuel Levinas favorisiert (aufgrund seiner Biographie) ganz stark andere Menschen und expliziert dies anhand von deren &#8222;Antlitz&#8220;.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Ich glaube dagegen, da\u00df Tiere und Pflanzen, jegliches Leid, eine scheinbar anonyme Lebensaufgabe, die monotone Arbeit oder allt\u00e4gliche Selbstverst\u00e4ndlichkeiten ebenso m\u00f6glich sind.\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Anspr\u00fcche aus der oder durch die Transzendenz habe ich absichtlich <em>als weitere Beispiele<\/em> weggelassen. Nicht weil sie mir als unm\u00f6glich erscheinen, sondern weil diese Anspr\u00fcche meines Erachtens <em>nicht zu den immanenten noch additiv hinzukommen, sondern sich nur in letzteren ausdr\u00fccken k\u00f6nnen<\/em>.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Ein Gott, der sich jenseits von Sein und Nicht-Sein befindet, kann keine Anspr\u00fcche f\u00fcr sich selbst erheben.\u00a0 \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><em>Als Verstrickter bin ich ein potentieller Tr\u00e4ger von Freiheit<\/em>; diese M\u00f6glichkeit wird aktualisiert, sobald ich mich als angesprochen erfahre und dadurch vollautomatisch zu einem Antwortenden werde.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">So entsteht die vollst\u00e4ndige Subjektivit\u00e4t, die wir nun genauer darstellen k\u00f6nnen:\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\"><em>Subjektivit\u00e4t\u00a0 \u00a0=\u00a0 \u00a0{ notwendigerweise Verstrickter + m\u00f6glicherweise Antwortender }<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Das Mich-als-angesprochen-Erfahren bildet den <em>Ursprung<\/em> meiner Freiheit. Sie selbst besteht in der <em>Entscheidung dar\u00fcber, wie ich antworte<\/em>. Ich tue dies\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; <em>mit der Philosophie des Subjekts autonom, selbstbestimmend oder eigenverantwortlich<\/em>, jedoch\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; <em>entgegen der Philosophie des Subjekts nicht aus mir selbst heraus, sondern &#8222;nur&#8220; in Form des Antwortens auf ein Mich-als -angesprochen-Erleben<\/em>.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Wir k\u00f6nnen die Freiheit somit<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; zwar als <em>Selbstbestimmung<\/em> verstehen;<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; sie ist aber <em>keine Eigenschaft oder F\u00e4higkeit von uns<\/em>, sondern<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; <em>das Geschenk des Sich-als-Angesprochen-Erfahrens<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vormodern verstanden sich die traditionellen Subjekte im wesentlichen als Gesch\u00f6pfe von Gottes Gnaden. Sie wurden \u2013 ohne zu wissen, warum und wozu \u2013 in eine vorgegebene (St\u00e4nde-)Ordnung hineingeboren, in der sie einen bestimmten Platz einzunehmen und eine definierte Aufgabe zu erf\u00fcllen hatten; das war ihre Essenz, ihr Wesen oder Was. Der Sinn des Lebens bestand [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4114,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4444","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages\/4444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/comments?post=4444"}],"version-history":[{"count":0,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages\/4444\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages\/4114"}],"wp:attachment":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/media?parent=4444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}