{"id":4460,"date":"2026-06-03T11:51:54","date_gmt":"2026-06-03T09:51:54","guid":{"rendered":"https:\/\/www.soukup.de\/selbst-denken\/?page_id=4460"},"modified":"2026-07-09T14:42:41","modified_gmt":"2026-07-09T12:42:41","slug":"1-8","status":"publish","type":"page","link":"https:\/\/www.soukup.de\/selbst-denken\/buch\/1-einleitung-kurz\/1-8\/","title":{"rendered":"1.9.  Zusammenfassung"},"content":{"rendered":"<p style=\"text-align: justify;\">In einem Lehrbuch werden die wichtigsten Punkte des Inhalts zusammenfassend wiederholt, damit die Studenten sich das neue Wissen m\u00f6glichst fest einpr\u00e4gen.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Bei uns geht es jedoch nicht um das Lernen von Sachverhalten, sondern um das Korrigieren von Denkformen. Dann hat eine Zusammenfassung meines Erachtens eine v\u00f6llig andere Aufgabe; n\u00e4mlich die, <em>ausgehend von dem neu erreichten Reflexionsniveau den bereits zur\u00fcckgelegten \u2013 aber erst jetzt sichtbar gewordenen \u2013 Weg verst\u00e4ndlich zu machen<\/em>:<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Wo befinden wir uns, und weshalb sind wir \u00fcberhaupt hierher gegangen?<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Was erweist sich aus dieser neuen Perspektive als falsch an dem alten Weg?<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Welche \u00fcberraschenden M\u00f6glichkeiten er\u00f6ffnet der neue?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">AD: &#8222;Ja; das w\u00fcrde mich auch interessieren . . .<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Ich habe ernsthaft versucht, Ihnen zu folgen; das war jedoch ein ziemliches Auf und Ab; gegenw\u00e4rtig erscheint mir Ihre Idee, die objektive Wirklichkeit canceln zu wollen, wieder einmal als absurd:<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Wir w\u00fcrden nach der Arbeit die Wohnung nicht finden, k\u00f6nnten keine Freunde wiedererkennen oder w\u00e4ren unf\u00e4hig, ein bestimmtes Buch im Regal zu suchen.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">All das funktioniert doch nur, weil<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; die objektive Wirklichkeit der Seienden nicht nur existiert, sondern<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; auch hinreichend stabil ist, so da\u00df<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; wir sie in der Psyche repr\u00e4sentieren k\u00f6nnen,<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8211; um uns an diesen Vorstellungen zu orientieren.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8218;Die Wohnung befindet sich dort hinten, das ist Moritz, und mein Buch hatte ich gestern hier abgelegt, so da\u00df es noch da sein m\u00fc\u00dfte.'&#8220;\u00a0 \u00a0\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Ich gehe gleich auf Ihren Einwand ein; aber es ist wohl hilfreich, wenn wir zuvor noch andeuten, worin nicht nur das Ziel dieser Zusammenfassung, sondern <em>die Perspektive all unserer \u00dcberlegungen<\/em> besteht.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Wir k\u00f6nnen das Bewu\u00dftsein sinnvoll in drei Teile aufgliedern, die in etwa den Registern von Jacqes Lacan entsprechen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr>\n<td style=\"background-color: #fcfccc; text-align: center; width: 100%;\" colspan=\"6\"><span style=\"color: #a37b02;\"><strong>Bewu\u00dftsein<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; background-color: #fcfccc; text-align: center;\" colspan=\"6\"><span style=\"color: #a37b02;\"><strong>Zeitigen \u2013 ein gerichteter Vollzug<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"text-align: center; background-color: #d0fccc; width: 33.3334%;\" colspan=\"2\"><strong>\u2013 &#8222;S\u00fcndenfall&#8220; \u2192<\/strong><\/td>\n<td style=\"width: 33.3334%; text-align: center; background-color: #d0fcfc;\" colspan=\"2\"><strong>\u2013 &#8222;Erl\u00f6sung&#8220; (?) \u2192<\/strong><\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"text-align: center; background-color: #d0fccc; width: 33.3334%;\" colspan=\"2\"><strong>\u2013 Diskretisieren \u2192<\/strong><\/td>\n<td style=\"text-align: center; background-color: #d0fcfc; width: 33.3334%;\" colspan=\"2\"><strong>\u2013 Integrieren (?) \u2192<\/strong><\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"text-align: center; background-color: #d0fccc; width: 33.3334%;\" colspan=\"2\"><strong>\u2013 Sagbar-Machen \u2192<\/strong><\/td>\n<td style=\"text-align: center; background-color: #d0fcfc; width: 33.3334%;\" colspan=\"2\"><strong>\u2013 Wahrer-Machen (?) \u2192<\/strong><\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 33.3334%; text-align: center; background-color: #d0fccc;\" colspan=\"2\"><strong>\u2013 Zeitigen zum Wissen \u2192<\/strong><\/td>\n<td style=\"width: 33.3334%; text-align: center; background-color: #d0fcfc;\" colspan=\"2\"><strong>\u2013 Zeit. z. wahreren Wissen (?) \u2192<\/strong><\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<td style=\"width: 16.6667%; text-align: center;\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #06bd00;\"><strong>Gegenwart<\/strong><\/span><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Vergangenheit<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Zukunft<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #06bd00;\"><strong>Reales<\/strong><\/span><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Symbolisches<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Imagin\u00e4res<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #06bd00;\"><strong>Ganzheit<\/strong><\/span><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Vielheit<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #06bd00;\"><strong>Erstmaliges<\/strong><\/span><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Wiederholtes<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Einheit des Zeitigens f\u00fcr das<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #06bd00;\"><strong>\u00a0<\/strong><\/span><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>sich daraus ergebende Selbst<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>Wissungen<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8211; Sedimentierungen<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong><span style=\"color: #ff0000;\">Subjektivit\u00e4t<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8212; Wahrnehmungen<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8212; Vorstellungen<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong><span style=\"color: #0000ff;\">Freiheit<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #06bd00;\"><em><strong>zeitigt sich in jedem Bewu\u00dftsein<\/strong><\/em><\/span><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>\u2193<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8211; Geschichten<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8211; <span style=\"color: #ff0000;\">Verstrickter<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #0000ff;\"><strong>Tr\u00e4ger des Aktes der Freiheit<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #ff0000;\"><strong>&#8222;mir oder mich&#8220;<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/strong><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><em><strong>denk-, wi\u00df- und sagbar<\/strong><\/em><\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8211; Sich-als-angesprochen-Erfahren<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #0000ff;\"><strong>Akt der Freiheit<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #0000ff;\"><strong>Antworten oder Handeln<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><strong>&#8211; <span style=\"color: #ff0000;\">Selbst<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #0000ff;\"><strong>Resultat des Aktes der Freiheit<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\">\u00a0<\/td>\n<td style=\"text-align: center; width: 33.3334%;\" colspan=\"2\"><span style=\"color: #ff0000;\"><strong>Selbst-Ich . . . Selbst-Wir<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Abbildung 1.9.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8222;<em>Das&#8220;<\/em> und nicht &#8222;<em>mein<\/em> Bewu\u00dftsein&#8220; zu schreiben, war Absicht, denn ich gehe als Subjektivit\u00e4t erst aus dem Bewu\u00dftsein hervor, so da\u00df\u00a0<em>ich die Subjektivit\u00e4t des Bewu\u00dftseins bin<\/em>.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Die Frage &#8222;<em>welchen<\/em> Bewu\u00dftseins?&#8220; stellt sich nicht. Keineswegs weil in unseren \u00dcberlegungen nur eines vorkommt, vielmehr weil Bewu\u00dftsein nicht zu den Wissungen geh\u00f6rt, aber nur diese gez\u00e4hlt werden k\u00f6nnen. Der Singular von Bewu\u00dftsein meint also nicht die Anzahl 1, sondern da\u00df es sich hierbei um eine Singularetantum handelt wie bei L\u00e4rm, Sprache oder Mathematik beispielsweise. Was es nicht mehrmals geben kann, ist auch nicht einmal m\u00f6glich.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Die meisten Ereignisphilosophien korrigieren die Tradition dahingehend, da\u00df die Wirklichkeit nicht vorhanden sei, sondern sich ereignen w\u00fcrde. Wir gehen noch dar\u00fcber hinaus und <em>bestreiten jegliche <\/em>(Form von)<em> Wirklichkeit, die etwas tut<\/em>; vielmehr <em>ist der Vollzug, das Tun, Sich-Ereignen oder -Zeitigen selbst die Wirklichkeit<\/em>.\u00a0 \u00a0 \u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Das widerpricht uns sponten, weil die traditionelle Philosohie eine solche der Substantive darstellt.<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8222;Was tanzt ihr?&#8220; &#8222;Einen Tanz.&#8220;<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8222;Was weht drau\u00dfen?&#8220; &#8222;Der Wind.&#8220;<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">&#8222;Was dreht sich dort?&#8220; &#8222;Ein Strudel.&#8220;<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Postmodern versuchen wir es anders:<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Das Tanzen ist der Tanz; das Wehen ist der Wind; das Strudeln ist der Strudel, das Flie\u00dfen der Flu\u00df und das Spielen das Spiel.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Es ist keine Wirklichkeit vorhanden, die unseren Bewu\u00dftseinen zugrunde liegt, sondern <em>sie sind alle dem gleichen Erstmaligen ausgesetzt;<\/em> auch das ist eine Singularetantum.\u00a0 \u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Das Zeitigen ist ein gerichteter, dauernder Vollzug; er f\u00fchrt zum Erstmaligen und \u00fcber dessen notwendige Diskretisierung hinaus zu den Subjektivit\u00e4ten, deren (verbales) Antworten oder Handeln wiederum dem Zeitigen angeh\u00f6rt.\u00a0\u00a0<\/p>\n<p class=\"Indent\" style=\"text-align: justify;\">Die Postmoderne geht also v\u00f6llig anders vor als die Tradition. Diese setzt voneinander getrennte Subjekte voraus und sucht nach Gemeinsamkeiten oder M\u00f6glichkeiten des Zusammenspiels.\u00a0 \u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einem Lehrbuch werden die wichtigsten Punkte des Inhalts zusammenfassend wiederholt, damit die Studenten sich das neue Wissen m\u00f6glichst fest einpr\u00e4gen. Bei uns geht es jedoch nicht um das Lernen von Sachverhalten, sondern um das Korrigieren von Denkformen. Dann hat eine Zusammenfassung meines Erachtens eine v\u00f6llig andere Aufgabe; n\u00e4mlich die, ausgehend von dem neu erreichten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3988,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4460","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages\/4460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/comments?post=4460"}],"version-history":[{"count":0,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages\/4460\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/pages\/3988"}],"wp:attachment":[{"href":"https:\/\/www.soukup.de\/selbst-denken\/wp-json\/wp\/v2\/media?parent=4460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}